{"id":3131,"date":"2016-08-15T17:46:22","date_gmt":"2016-08-15T15:46:22","guid":{"rendered":"https:\/\/jamtechcorp.com\/blog\/?p=1979"},"modified":"2016-08-15T17:46:22","modified_gmt":"2016-08-15T15:46:22","slug":"exito-xiaomi","status":"publish","type":"post","link":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/","title":{"rendered":"Las claves del \u00e9xito de Xiaomi"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Xiaomi es la segunda startup m\u00e1s exitosa, justo por detr\u00e1s de Uber<\/h2>\n<p style=\"text-align: justify;\">Xiaomi \u00a0naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone \u00a0a nivel mundial, mientras que en China \u2013su mercado interno- ya logr\u00f3 desbancar a Samsung en el primer lugar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Si no fuera poco, Xiaomi ahora se propone conquistar el mercado latinoamericano, queri\u00e9ndose expandir en Brasil y otros mercados occidentales.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Con apenas cinco a\u00f1os de fundada ya estaba valorada en 46 mil millones de d\u00f3lares y se ubicaba como la segunda startups m\u00e1s exitosa del mundo, justo por detr\u00e1s de Uber, la compa\u00f1\u00eda estadounidense \u00a0que ofrece servicios de taxis seguros y con bajos precios, y estaba valorada en unos 50 mil millones de d\u00f3lares, qued\u00e1ndose en el primer lugar, esto seg\u00fan una lista publicada en agosto de 2015 por el diario The Wall Street Journal con las 108 startups m\u00e1s exitosas del mundo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>\u00bfC\u00f3mo ha logrado el \u00e9xito?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Pues hay varias claves del \u00e9xito de este fabricante chino, pero quiz\u00e1s la principal raz\u00f3n\u00a0 son sus precios accesibles a la poblaci\u00f3n, ofreciendo celulares inteligentes de gama alta por precios de gama media a\u00fan as\u00ed obteniendo ganancias. \u00a0Y otra vez nos preguntamos, \u00bfc\u00f3mo lo hace?, pues ellos tratan de vender sus productos al precio de costo m\u00e1s cercano al de su producci\u00f3n, luego sus costos de fabricaci\u00f3n van cayendo gracias a los avances tecnol\u00f3gicos y van adquiriendo sus ganancias.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">S\u00ed, como lo est\u00e1s leyendo. Tiene una gran l\u00ednea de productos, celulares de gama alta por un precio muy bajo. Adem\u00e1s ofrece televisores, UHD y routers, todos a precios muy m\u00f3dicos, por ende son vendidos con regularidad en China.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El Redmi Note es un phablet de 5,5 pulgadas con un procesador octa-core que ofrece un rendimiento \u00f3ptimo y se puede adquirir por al menos unos 115 euros, dependiendo la zona, es decir, es un precio muy por debajo a lo que cuesta ese producto pero de otro fabricante.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A pesar de su \u00e9xito, Xiaomi no es una empresa que gasta mucho dinero en marketing, solo invierten en sitios donde puedan estar sus compradores fieles, por ejemplo, en redes sociales y p\u00e1ginas web. Adem\u00e1s de tener \u201cMi Fans\u201d, que son un grupo de personas que est\u00e1n enamorados de sus productos y los siguen a cada evento, conferencia o lanzamiento de la compa\u00f1\u00eda, y como casi todo en la actualidad se mueve con Internet, el amor hac\u00eda Xiaomi rompe las barreras y tienen fan\u00e1ticos en otros pa\u00edses fuera de Asia.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El interfaz de usuario tambi\u00e9n es una clave para que Xiaomi adquiriera el \u00e9xito que tiene en la actualidad. Este producto ofrece una ROM basada en Android ofrece caracter\u00edsticas adiciones, adem\u00e1s gestos de navegaci\u00f3n y temas para personalizar el interfaz como m\u00e1s te guste. Puede adem\u00e1s ser descargado en otros tel\u00e9fonos con sistema operativo Android, no necesariamente tiene que ser Smartphone de Xiaomi, pero debes saber si tu celular dispone de \u00a0ROM.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Los fundadores de Xiaomi son Hong Feng,\u00a0Lei Jun,\u00a0Zhou Guangping,\u00a0Li Wanqiang,\u00a0Huang Jiangji,\u00a0Lin Bin,\u00a0Liu De,\u00a0Wang Chuan y su director ejecutivo desde hace seis a\u00f1os, la misma cantidad de tiempo cuando empez\u00f3 en funcionamiento la empresa, Lei Jun.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/mifans.es\/las-cinco-claves-del-exito-de-xiaomi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fuente:<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xiaomi es la segunda startup m\u00e1s exitosa, justo por detr\u00e1s de Uber Xiaomi \u00a0naci\u00f3 en abril del a\u00f1o 2010 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3132,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[179],"tags":[368,168,209,190,450,370,372,454],"class_list":["post-3131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-startups","tag-dinero","tag-emprendimiento","tag-empresa","tag-exito","tag-marca","tag-negocio","tag-producto","tag-smartphone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las claves del \u00e9xito de Xiaomi - JAM Tech<\/title>\n<meta name=\"description\" content=\"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las claves del \u00e9xito de Xiaomi - JAM Tech\" \/>\n<meta property=\"og:description\" content=\"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/\" \/>\n<meta property=\"og:site_name\" content=\"JAM Tech\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-15T15:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jamtechblog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jamtechblog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/\",\"name\":\"Las claves del \u00e9xito de Xiaomi - JAM Tech\",\"isPartOf\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg\",\"datePublished\":\"2016-08-15T15:46:22+00:00\",\"author\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21\"},\"description\":\"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo\",\"breadcrumb\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg\",\"contentUrl\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jamtechcorp.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las claves del \u00e9xito de Xiaomi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#website\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/\",\"name\":\"JAM Tech\",\"description\":\"Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jamtechcorp.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21\",\"name\":\"jamtechblog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g\",\"caption\":\"jamtechblog\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las claves del \u00e9xito de Xiaomi - JAM Tech","description":"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/","og_locale":"es_ES","og_type":"article","og_title":"Las claves del \u00e9xito de Xiaomi - JAM Tech","og_description":"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo","og_url":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/","og_site_name":"JAM Tech","article_published_time":"2016-08-15T15:46:22+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg","type":"image\/jpeg"}],"author":"jamtechblog","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jamtechblog","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/","url":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/","name":"Las claves del \u00e9xito de Xiaomi - JAM Tech","isPartOf":{"@id":"https:\/\/jamtechcorp.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage"},"image":{"@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage"},"thumbnailUrl":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg","datePublished":"2016-08-15T15:46:22+00:00","author":{"@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21"},"description":"Xiaomi naci\u00f3 en abril del a\u00f1o 2010 y en poco tiempo ha logrado posicionarse en los primeros lugares de los mercados de fabricantes de Smartphone en el mundo","breadcrumb":{"@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#primaryimage","url":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg","contentUrl":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2016\/08\/Xiaomi-Logo-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/jamtechcorp.com\/blog\/exito-xiaomi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jamtechcorp.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Las claves del \u00e9xito de Xiaomi"}]},{"@type":"WebSite","@id":"https:\/\/jamtechcorp.com\/blog\/#website","url":"https:\/\/jamtechcorp.com\/blog\/","name":"JAM Tech","description":"Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jamtechcorp.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21","name":"jamtechblog","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g","caption":"jamtechblog"}}]}},"_links":{"self":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts\/3131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/comments?post=3131"}],"version-history":[{"count":0,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts\/3131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/media\/3132"}],"wp:attachment":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/media?parent=3131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/categories?post=3131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/tags?post=3131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}