{"id":2997,"date":"2017-04-20T22:54:35","date_gmt":"2017-04-20T20:54:35","guid":{"rendered":"https:\/\/jamtechcorp.com\/blog\/?p=2377"},"modified":"2017-04-20T22:54:35","modified_gmt":"2017-04-20T20:54:35","slug":"tener-empleados-motivados","status":"publish","type":"post","link":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/","title":{"rendered":"C\u00f3mo tener a tus empleados motivados"},"content":{"rendered":"<p>Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo. No solo de forma <strong>eficiente<\/strong>, sino que se va a entregar con nuevas ideas y ayudar\u00e1 a lograr los objetivos que se trace la empresa.<\/p>\n<p>Los trabajadores cuando est\u00e1n malhumorados hacen el ambiente muy pesado y nada agradable.\u00a0 Sin embargo, no siempre ser\u00e1 culpa de la empresa. Pero s\u00ed debes tomar cartas en el asunto cuando se vuelve cotidiano, sin duda algo anda mal.<\/p>\n<p><strong>Cuando se quiere tener a los empleados motivados siempre se debe pensar en sus situaciones particulares.<\/strong>\u00a0Cada quien vive una realidad distinta y nunca es f\u00e1cil lograr que est\u00e9 del todo contento.<\/p>\n<p>Si eres un emprendedor y quieres tener un ambiente laboral agradable. Ese que notas en el primer d\u00eda o la primera semana de trabajo, pero que con el paso del tiempo va quedando de lado, sigue leyendo este post de<a href=\"https:\/\/jamtechcorp.com\/\"> JAM Tech<\/a> en el que queremos ofrecerte unas t\u00e9cnicas para lograr que tus trabajadores siempre est\u00e9n motivados.<\/p>\n<p><strong>Ser el jefe engloba una responsabilidad muy grande.<\/strong>\u00a0En muchas ocasiones puede ser el principal responsable de que haya o no un buen ambiente dentro del \u00e1rea laboral. Al ser el gu\u00eda debe siempre tener claridad para poder solucionar los problemas que se van a presentar.<\/p>\n<p>&nbsp;<\/p>\n<h2>Empleados motivados:<\/h2>\n<ul>\n<li><strong>Dar retroalimentaci\u00f3n <\/strong><\/li>\n<\/ul>\n<p>As\u00ed como le puedes hacer una tarea que hizo mal al trabajador, tambi\u00e9n debes tener la sapiencia para <strong>reconocer un trabajo bien hecho<\/strong>. Hacerle saber que su asignaci\u00f3n la realiz\u00f3 de la forma correcta le llena de confianza.<\/p>\n<p>Mientras m\u00e1s confianza sienta el trabajador se va a sentir con la libertad de proponer ideas. Adem\u00e1s podr\u00e1 ayudar a otro compa\u00f1ero que no destaque tanto y tendr\u00e1s un ambiente de trabajo en equipo en el que todos buscan los mismos objetivos. Pero para lograrlo es necesario hacerles ver los aspectos positivos.<\/p>\n<p>En muchas empresas estas actitudes no se acostumbran ya que \u201ces su trabajo y por \u00e9l se le paga\u201d. Pero all\u00ed es donde los problemas de motivaci\u00f3n son graves o simplemente las personas hacen sus tareas de forma mec\u00e1nica, sin ir m\u00e1s all\u00e1, sino solo lo que le pide.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Genera confianza<\/strong><\/li>\n<\/ul>\n<p>Siempre conversar con el grupo de empleados que tienes a cargo es muy valioso. No solo cuando de plantear estrategias se trata. Sino por ejemplo almorzar una vez a la semana con tus trabajadores. Ir por un caf\u00e9, un simple break en el horario laboral ser\u00e1 bienvenido por ellos.<\/p>\n<p>Preocuparte por sus asuntos personales. Preguntar por su familia y ser muy receptivo con los problemas le permitir\u00e1 a tus subalternos verte como un\u00a0 <strong>jefe cercano<\/strong>. Con el que pueden conversar sobre cualquier situaci\u00f3n que tenga. No solo de la oficina sino pedir alg\u00fan consejo sobre una situaci\u00f3n que est\u00e9 viviendo.<\/p>\n<p>Esa vieja imagen del jefe lejano, autoritario, que no conoce a sus trabajadores debe quedar en el olvido. Debe ser todo lo contrario, ser cercano, flexible y sobre todo saber cada aspecto de tu empleado es muy importante y ellos lo saben apreciar, porque se van a sentir importantes.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Crea premios <\/strong><\/li>\n<\/ul>\n<p>A las personas les gusta que los premien por su buen desempe\u00f1o. Independientemente de las labores que realice que haya una gratificaci\u00f3n ser\u00e1 bien recibida.<\/p>\n<p>Hay miles de empresas en el mundo que tienen <strong>programas de gratificaci\u00f3n<\/strong> en la que hay diferentes premios de acuerdo a los objetivos que alcance, tanto los individuales como grupales. Debes saber que no solo se trata de dinero, no a todos es lo que llena, aunque siempre viene bien. Pero si prefieres hacerlo de esa manera debe ser un monto que de verdad motive.<\/p>\n<p>Incluso los peque\u00f1os detalles pueden marcar diferencias. Dejar un chocolate en el puesto de cada quien. Invitar un helado, almuerzo tambi\u00e9n son bien recibidos. Entradas para un evento relacionado con su \u00e1rea, para el concierto de su cantante favorito. Descuentos especiales en consumos tambi\u00e9n son valiosos.<\/p>\n<p>Si se trata de una cultura m\u00e1s empresarial, viajes de fin de semana. El ir de intercambio a otra sede de la empresa en un pa\u00eds o regi\u00f3n diferente al que se encuentra para que conozca los mecanismos y que ello le permita desempe\u00f1ar mejor su trabajo son siempre premios que los trabajadores deben recibir.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Programa de ascensos <\/strong><\/li>\n<\/ul>\n<p>Una de las metas que tienen los empleados es llegar lo m\u00e1s lejos posible. Que en un futuro sean los jefes o est\u00e9n a cargo de un \u00e1rea en la que puedan mostrar todas las habilidades que tienen. Si los trabajadores sienten que pueden llegar ese objetivo se van a entregar mucho m\u00e1s.<\/p>\n<p>No hay nada peor que en los puestos gerenciales est\u00e9n ocupados por los amigos del jefe no por sus aptitudes, sino por ser condescendiente con los superiores. Peor sucede cuando son los familiares, a pesar de que no son los m\u00e1s calificados.<\/p>\n<p>Este es un elemento que debes tomar en cuenta. Debes ser muy objetivo al momento de postular a las personas que merecen un ascenso no es el que te cae mejor, sino la persona m\u00e1s capacitada, aunque en lo personal no sean tan cercanos.<\/p>\n<p>Si no haces esto no tendr\u00e1s a tus empleados motivados.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Ser flexibles <\/strong><\/li>\n<\/ul>\n<p>Flexibilidad con horarios, con situaciones e incluso con la posibilidad de que un d\u00eda pueda trabajar desde casa o solo medio turno porque debe cumplir con asuntos personales te hace quedar bien con tus empelados. Por supuesto que no se debe convertir en una costumbre, porque si no tendr\u00e1s un ausentismo muy alto, pero s\u00ed cuando sean situaciones que lo ameriten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Debes perseverar<\/strong><\/p>\n<p>Cuando eres el l\u00edder de una empresa siempre debes buscar las formas para que el ambiente sea el mejor. Es un trabajo continuo que no tiene descanso. De esta manera podr\u00e1s reducir considerablemente la rotaci\u00f3n del personal y tener a tus empleados motivados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[233,419,209,398,545],"class_list":["post-2997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","tag-consejos","tag-empleados","tag-empresa","tag-relaciones-laborales","tag-rendimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados<\/title>\n<meta name=\"description\" content=\"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados\" \/>\n<meta property=\"og:description\" content=\"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/\" \/>\n<meta property=\"og:site_name\" content=\"JAM Tech\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-20T20:54:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jamtechblog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jamtechblog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/\",\"name\":\"En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados\",\"isPartOf\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg\",\"datePublished\":\"2017-04-20T20:54:35+00:00\",\"author\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21\"},\"description\":\"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo\",\"breadcrumb\":{\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg\",\"contentUrl\":\"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg\",\"width\":837,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jamtechcorp.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo tener a tus empleados motivados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#website\",\"url\":\"https:\/\/jamtechcorp.com\/blog\/\",\"name\":\"JAM Tech\",\"description\":\"Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jamtechcorp.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21\",\"name\":\"jamtechblog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g\",\"caption\":\"jamtechblog\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados","description":"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/","og_locale":"es_ES","og_type":"article","og_title":"En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados","og_description":"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo","og_url":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/","og_site_name":"JAM Tech","article_published_time":"2017-04-20T20:54:35+00:00","og_image":[{"width":837,"height":720,"url":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg","type":"image\/jpeg"}],"author":"jamtechblog","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jamtechblog","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/","url":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/","name":"En JAM Tech te ense\u00f1amos c\u00f3mo tener a tus empleados motivados","isPartOf":{"@id":"https:\/\/jamtechcorp.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage"},"image":{"@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage"},"thumbnailUrl":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg","datePublished":"2017-04-20T20:54:35+00:00","author":{"@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21"},"description":"Tarea dif\u00edcil y complicada, es mantener a los empleados motivados siempre, para que de esta manera puedan realizar mucho mejor su trabajo","breadcrumb":{"@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#primaryimage","url":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg","contentUrl":"https:\/\/jamtechcorp.com\/blog\/wp-content\/uploads\/2017\/04\/adult-1374105_960_720.jpg","width":837,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/jamtechcorp.com\/blog\/tener-empleados-motivados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jamtechcorp.com\/blog\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo tener a tus empleados motivados"}]},{"@type":"WebSite","@id":"https:\/\/jamtechcorp.com\/blog\/#website","url":"https:\/\/jamtechcorp.com\/blog\/","name":"JAM Tech","description":"Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jamtechcorp.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/17a77a0f91d506335e5144025dcc8d21","name":"jamtechblog","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jamtechcorp.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11a1115ba30372d08c78ab6123c83688d2a881a581db6b16b11baee6c5c26a4d?s=96&d=mm&r=g","caption":"jamtechblog"}}]}},"_links":{"self":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts\/2997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/comments?post=2997"}],"version-history":[{"count":0,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/posts\/2997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/media\/2998"}],"wp:attachment":[{"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/media?parent=2997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/categories?post=2997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jamtechcorp.com\/blog\/wp-json\/wp\/v2\/tags?post=2997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}